{"id":44535,"date":"2026-01-29T11:08:32","date_gmt":"2026-01-29T09:08:32","guid":{"rendered":"https:\/\/prindustry.com\/prindustry-platform\/assortment-managament\/"},"modified":"2026-09-01T15:39:21","modified_gmt":"2026-09-01T13:39:21","slug":"assortimentsbeheer","status":"publish","type":"page","link":"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/","title":{"rendered":"Assortimentsbeheer"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]\t<style>#pr-hero-1 .prhero-main{width:100% !important;right:-13% !important;transform:rotate(3.8deg) !important;}#pr-hero-1 .prhero-main:hover{transform:rotate(3.8deg) translateY(-8px) scale(1.015) !important}<\/style>\t<section id=\"pr-hero-1\" class=\"prhero prhero--home prhero--imgs-1\">\n\t\t<div class=\"prhero-bg-shadow\"><\/div>\n\n\t\t<div class=\"prhero-inner\">\n\t\t\t<div class=\"prhero-copy\">\n\t\t\t\t\t\t\t\t\t<span class=\"prhero-eyebrow\">Bouw je eigen productcatalogus<\/span>\n\t\t\t\t\t\t\t\t<h1>Assortimentsbeheer print<\/h1>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Beheer producten, opties en prijzen vanuit \u00e9\u00e9n centrale omgeving en publiceer ze direct naar je webshop, offertes of de Marktplaats.<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"prhero-actions\">\n\t\t\t\t\t\t<a href=\"https:\/\/prindustry.com\/nl\/online-demo-aanvragen\/\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"prhero-btn prhero-btn-primary\">Vraag een demo aan<\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"prhero-visual\">\n\t\t\t\t<div class=\"prhero-glow\"><\/div>\n\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"513\" src=\"https:\/\/prindustry.com\/wp-content\/uploads\/2026\/07\/Product-Wizard-Samenvatting-van-wat-gemaakt-is-en-gegenereerd-gaat-worden-1024x513.webp\" class=\"prhero-screen prhero-main not-transparent\" alt=\"Een samenvatting van productvarianten gemakkelijk te vinden in de product wizard\" loading=\"eager\" fetchpriority=\"high\" srcset=\"https:\/\/prindustry.com\/wp-content\/uploads\/2026\/07\/Product-Wizard-Samenvatting-van-wat-gemaakt-is-en-gegenereerd-gaat-worden-1024x513.webp 1024w, https:\/\/prindustry.com\/wp-content\/uploads\/2026\/07\/Product-Wizard-Samenvatting-van-wat-gemaakt-is-en-gegenereerd-gaat-worden-300x150.webp 300w, https:\/\/prindustry.com\/wp-content\/uploads\/2026\/07\/Product-Wizard-Samenvatting-van-wat-gemaakt-is-en-gegenereerd-gaat-worden-768x385.webp 768w, https:\/\/prindustry.com\/wp-content\/uploads\/2026\/07\/Product-Wizard-Samenvatting-van-wat-gemaakt-is-en-gegenereerd-gaat-worden-1536x770.webp 1536w, https:\/\/prindustry.com\/wp-content\/uploads\/2026\/07\/Product-Wizard-Samenvatting-van-wat-gemaakt-is-en-gegenereerd-gaat-worden-1000x500.webp 1000w, https:\/\/prindustry.com\/wp-content\/uploads\/2026\/07\/Product-Wizard-Samenvatting-van-wat-gemaakt-is-en-gegenereerd-gaat-worden-670x335.webp 670w, https:\/\/prindustry.com\/wp-content\/uploads\/2026\/07\/Product-Wizard-Samenvatting-van-wat-gemaakt-is-en-gegenereerd-gaat-worden.webp 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-has-transparency=\"false\" data-dominant-color=\"cbd5de\" style=\"--dominant-color: #cbd5de;\" \/>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/section>\n\t[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;pim&#8221; row_name=&#8221;Save Time&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;52342&#8243; image_size=&#8221;full&#8221; max_width=&#8221;150%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Stel je printcatalogus samen&#8221; font_container=&#8221;tag:h2|font_size:34px|text_align:left|color:%23172e4b&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1787645901634{margin-bottom: 30px !important;}&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]Stel je online assortiment samen: koppel met producenten of bouw het zelf op in het <a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/\" target=\"_blank\" rel=\"noopener\">Prindustry Platform.<\/a> Het samenstellen verloopt via de modulaire Product Wizard. Deze tool helpt je stap voor stap bij het opbouwen van een volledig product met slimme boxes &amp; options. Een box is bijvoorbeeld:[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-minus\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"10px\" data-alignment=\"left\"> \n<ul>\n<li>Formaat<\/li>\n<li>Bedrukking<\/li>\n<li>Materiaal<\/li>\n<li>Gewicht<\/li>\n<li>Afwerking<\/li>\n<\/ul>\n <\/div>[vc_column_text]Veel productcategorie\u00ebn bevatten al vooraf ingevulde boxes. Die kun je eenvoudig aanpassen of uitbreiden. Zo bouw je een productcatalogus die past bij jouw assortiment en productie.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#fafafa&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; row_name=&#8221;Save Time&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Koppel direct de juiste prijs&#8221; font_container=&#8221;tag:h3|font_size:34px|text_align:left|color:%23172e4b&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1770041678510{margin-bottom: 30px !important;}&#8221;][vc_column_text]In de Product Wizard koppel je direct een passende prijsstructuur aan elk product.<br \/>\nJe hebt twee opties:[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-arrow-right\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"10px\" data-alignment=\"left\"> \n<ul>\n<li>Eigen calculatie: de prijs wordt automatisch berekend op basis van je eigen machines, productie-instellingen en materiaalkosten uit de <a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/calculatietool\/\" target=\"_blank\" rel=\"noopener\">calculatietool<\/a>.<\/li>\n<li>Extern aanbod: je neemt het assortiment van een externe producent over \u2013 inclusief hun vaste prijzen of prijstabellen.<\/li>\n<\/ul>\n <\/div>[vc_column_text]Daarna stel je per product nog in:[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-minus\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"10px\" data-alignment=\"left\"> \n<ul>\n<li>Marges: stel aangepaste marges in per product of per reseller.<\/li>\n<li>Prijstabellen: bepaal hoe prijzen worden weergegeven.<\/li>\n<\/ul>\n <\/div>[vc_column_text]Zo maak je elk product direct beschikbaar met de juiste prijsweergave.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;52345&#8243; image_size=&#8221;full&#8221; max_width=&#8221;150%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Right&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; row_name=&#8221;Save Time&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;52348&#8243; image_size=&#8221;full&#8221; max_width=&#8221;150%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Zet je catalogus om in verkoopmogelijkheden&#8221; font_container=&#8221;tag:h3|font_size:34px|text_align:left|color:%23172e4b&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1769524735965{margin-bottom: 30px !important;}&#8221;][vc_column_text]Vanuit \u00e9\u00e9n centrale plek maak je je aanbod beschikbaar via:[\/vc_column_text]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-check\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"20px\" data-alignment=\"left\"> \n<ul>\n<li>je eigen <a href=\"https:\/\/prindustry.com\/nl\/whitelabelshop\/\" target=\"_blank\" rel=\"noopener\">webshop<\/a> of bestelportaal<\/li>\n<li>de <a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/marktplaats\/\" target=\"_blank\" rel=\"noopener\">Marktplaats<\/a> voor resellers<\/li>\n<li><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/offertebeheer\/\" target=\"_blank\" rel=\"noopener\">offertes<\/a> op maat voor klanten<\/li>\n<li>je eigen <a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/api-koppeling-drukwerk\/\" target=\"_blank\" rel=\"noopener\">API<\/a> \u2013 publiceer je assortiment automatisch naar externe systemen<\/li>\n<\/ul>\n <\/div>[vc_column_text]Zo breng je je assortiment gestructureerd \u00e9n effici\u00ebnt naar je verkoopkanalen \u2013 met actuele prijzen en configuraties.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#fafafa&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; row_name=&#8221;Save Time&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Van sterk aanbod naar schaalbaar succes&#8221; font_container=&#8221;tag:h3|font_size:34px|text_align:left|color:%23172e4b&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1769525086603{margin-bottom: 30px !important;}&#8221;][vc_column_text]Veel grafimedia bedrijven hebben een sterk aanbod, maar vinden het lastig om dit gestructureerd \u00e9n breed beschikbaar te maken. Het Prindustry Platform helpt je om van je assortiment een schaalbaar verkoopinstrument te maken. Je beheert alles op \u00e9\u00e9n plek, presenteert je aanbod professioneel en bereikt meer klanten \u2013 zonder tijdrovende processen.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#f16721&#8243; icon_family=&#8221;default_arrow&#8221; text=&#8221;BEKIJK DE PRAKTIJKCASE&#8221; url=&#8221;https:\/\/prindustry.com\/nl\/use-cases\/assortiment-verkopen-aan-resellers-en-printmanagers\/&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;56180&#8243; image_size=&#8221;full&#8221; max_width=&#8221;150%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Right&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#fafafa&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;1%&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Hoe past dit in het Prindustry Platform?&#8221; font_container=&#8221;tag:h2|text_align:center|color:%23172e4b&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p dir=\"ltr\">Het Prindustry Platform is \u00e9\u00e9n <a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/\" target=\"_blank\" rel=\"noopener\">SaaS-beheerplatform<\/a> voor printmanagement.<br \/>\nHet verbindt alle stappen in je proces, van assortiment en calculatie tot orders en facturatie.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-20-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;52354&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"pr-table-wrap\"><table class=\"pr-table pr-table--bold1\"><thead><tr><th class=\"pr-table__c1\">Feature<\/th><th>Wat kun je ermee?<\/th><\/tr><\/thead><tbody><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Assortimentsbeheer<\/a><\/td><td data-th=\"Wat kun je ermee?\">Bouw je productcatalogus en beheer je producten, opties en prijzen centraal.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/api-koppeling-drukwerk\/\" target=\"_blank\" rel=\"noopener noreferrer\">API<\/a><\/td><td data-th=\"Wat kun je ermee?\">Eigen API voor orders: deel je assortiment met externe webshops en systemen.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/brandportal-software\/media-manager-bestandsbeheer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bestandsbeheer<\/a><\/td><td data-th=\"Wat kun je ermee?\">Al je bestanden op \u00e9\u00e9n plek. Gebruik ze direct in templates, offertes, orders.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/brandportal-software\/budgetbeheer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Budgetbeheer<\/a><\/td><td data-th=\"Wat kun je ermee?\">Geef gebruikers een eigen budget en houd grip op de uitgaven.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/calculatietool\/\" target=\"_blank\" rel=\"noopener noreferrer\">Calculatie<\/a><\/td><td data-th=\"Wat kun je ermee?\">Bereken kost- en verkoopprijzen op basis van je eigen machines en materialen.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/online-editor-pitchprint\/\" target=\"_blank\" rel=\"noopener noreferrer\">Editor<\/a><\/td><td data-th=\"Wat kun je ermee?\">Laat gebruikers zelf materialen personaliseren binnen vaste kaders.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\">Facturatie<\/td><td data-th=\"Wat kun je ermee?\">Van order naar factuur, met koppeling naar je boekhoudprogramma.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/gebruikersbeheer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gebruikersbeheer<\/a><\/td><td data-th=\"Wat kun je ermee?\">Bepaal per gebruiker de toegang, rollen en rechten binnen de bestelomgeving.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/marktplaats\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marktplaats<\/a><\/td><td data-th=\"Wat kun je ermee?\">Koop en verkoop op het onafhankelijke platform voor inkopers en producenten.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/offertebeheer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Offertebeheer<\/a><\/td><td data-th=\"Wat kun je ermee?\">Maak snel offertes met actuele prijzen en zet ze na akkoord om in een order.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/orderbeheer\/\" target=\"_blank\" rel=\"noopener noreferrer\">Orderbeheer<\/a><\/td><td data-th=\"Wat kun je ermee?\">Automatiseer je orderverwerking van bestelling tot productie.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/preflight-tool-in-prindustry-software-slim-bestanden-controleren-voor-productie\/\" target=\"_blank\" rel=\"noopener noreferrer\">Preflight<\/a><\/td><td data-th=\"Wat kun je ermee?\">Controleer drukwerkbestanden automatisch op technische fouten.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/projecten\/\" target=\"_blank\" rel=\"noopener noreferrer\">Projectbeheer<\/a><\/td><td data-th=\"Wat kun je ermee?\">Breng alle onderdelen van een project samen: prijzen, communicatie, orders.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\"><a href=\"https:\/\/prindustry.com\/nl\/whitelabelshop\/storefront\/\" target=\"_blank\" rel=\"noopener noreferrer\">Storefronts<\/a><\/td><td data-th=\"Wat kun je ermee?\">Richt meerdere bestelomgevingen in en beheer ze vanuit \u00e9\u00e9n systeem.<\/td><\/tr><tr><td class=\"pr-table__c1\" data-th=\"Feature\">Voorraadbeheer<\/td><td data-th=\"Wat kun je ermee?\">Houd je voorraad actueel en laat zien welke producten beschikbaar zijn.<\/td><\/tr><\/tbody><\/table><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;52357&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#efefef&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;10&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-lg-11 vc_col-md-11 vc_col-xs-12&#8243;][vc_custom_heading text=&#8221;Aan de slag met assortimentsbeheer?&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23172e4b&#8221; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-lg-11 vc_col-md-11 vc_col-xs-12&#8243;][vc_column_text css=&#8221;.vc_custom_1769518086901{padding-right: 10% !important;}&#8221;]Onze software-experts laten je graag zien hoe het platform werkt voor jouw organisatie.<\/p>\n<p>Plan een demo in en ontdek hoe je producten slimmer beheert \u00e9n verkoopt.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;fontawesome&#8221; text=&#8221;CONTACTFORMULIER&#8221; margin_top=&#8221;20px&#8221; url=&#8221;https:\/\/prindustry.com\/nl\/contact\/&#8221; margin_right=&#8221;20px&#8221; icon_fontawesome=&#8221;fa fa-wpforms&#8221;][nectar_btn size=&#8221;medium&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;fontawesome&#8221; text=&#8221;ONLINE DEMO AANVRAGEN&#8221; margin_top=&#8221;20px&#8221; url=&#8221;https:\/\/prindustry.com\/nl\/online-demo-aanvragen\/&#8221; margin_right=&#8221;20px&#8221; icon_fontawesome=&#8221;fa fa-desktop&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;fontawesome&#8221; text=&#8221;BEL NAAR PRINDUSTRY&#8221; margin_top=&#8221;10px&#8221; url=&#8221;tel:+31208223536&#8243; icon_fontawesome=&#8221;fa fa-phone&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;5px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;52360&#8243; image_size=&#8221;full&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;right&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":32221,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-44535","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assortimentsbeheer voor print en drukwerk | Bouw je catalogus<\/title>\n<meta name=\"description\" content=\"Stel je online printassortiment samen. Configureer producten, voeg prijsregels toe en publiceer je aanbod in webshop of Marktplaats.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assortimentsbeheer voor print en drukwerk | Bouw je catalogus\" \/>\n<meta property=\"og:description\" content=\"Stel je online printassortiment samen. Configureer producten, voeg prijsregels toe en publiceer je aanbod in webshop of Marktplaats.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/\" \/>\n<meta property=\"og:site_name\" content=\"Prindustry | Software Brandportals en Webshops | We love to connect\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Prindustry\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T13:39:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@prindustry\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assortimentsbeheer voor print en drukwerk | Bouw je catalogus","description":"Stel je online printassortiment samen. Configureer producten, voeg prijsregels toe en publiceer je aanbod in webshop of Marktplaats.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/","og_locale":"nl_NL","og_type":"article","og_title":"Assortimentsbeheer voor print en drukwerk | Bouw je catalogus","og_description":"Stel je online printassortiment samen. Configureer producten, voeg prijsregels toe en publiceer je aanbod in webshop of Marktplaats.","og_url":"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/","og_site_name":"Prindustry | Software Brandportals en Webshops | We love to connect","article_publisher":"https:\/\/www.facebook.com\/Prindustry\/","article_modified_time":"2026-09-01T13:39:21+00:00","twitter_card":"summary_large_image","twitter_site":"@prindustry","twitter_misc":{"Geschatte leestijd":"4 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/","url":"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/","name":"Assortimentsbeheer voor print en drukwerk | Bouw je catalogus","isPartOf":{"@id":"https:\/\/prindustry.com\/nl\/#website"},"datePublished":"2026-01-29T09:08:32+00:00","dateModified":"2026-09-01T13:39:21+00:00","description":"Stel je online printassortiment samen. Configureer producten, voeg prijsregels toe en publiceer je aanbod in webshop of Marktplaats.","breadcrumb":{"@id":"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/assortimentsbeheer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prindustry.com\/nl\/"},{"@type":"ListItem","position":2,"name":"ERP Printmanagement","item":"https:\/\/prindustry.com\/nl\/erp-printmanagement-platform\/"},{"@type":"ListItem","position":3,"name":"Assortimentsbeheer"}]},{"@type":"WebSite","@id":"https:\/\/prindustry.com\/nl\/#website","url":"https:\/\/prindustry.com\/nl\/","name":"Prindustry | Software Brandportals en Webshops | We love to connect","description":"We love to connect","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prindustry.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/pages\/44535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/comments?post=44535"}],"version-history":[{"count":10,"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/pages\/44535\/revisions"}],"predecessor-version":[{"id":56727,"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/pages\/44535\/revisions\/56727"}],"up":[{"embeddable":true,"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/pages\/32221"}],"wp:attachment":[{"href":"https:\/\/prindustry.com\/nl\/wp-json\/wp\/v2\/media?parent=44535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}