{"id":9768,"date":"2024-05-24T09:10:27","date_gmt":"2024-05-24T07:10:27","guid":{"rendered":"https:\/\/prindustry.com\/online-editor-chili-publisher\/"},"modified":"2026-07-10T14:33:45","modified_gmt":"2026-07-10T12:33:45","slug":"online-editor-chili-publisher","status":"publish","type":"post","link":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/","title":{"rendered":"CHILI: Konsistente Markenkommunikation"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]<!--more--><\/p>\n<h2>Online-Editor in Ihrem Brand Portal<\/h2>\n<ul>\n<li>Personalisierung der Kommunikation mit Corporate Identity Management<\/li>\n<li>Druck-Ausgabe: druckfertige Datei<br \/>\nOnline Media-Ausgabe: dynamische Formate<\/li>\n<li>Ideal f\u00fcr Integration in das Prindustry <a href=\"https:\/\/prindustry.com\/de\/brand-portal-software\/\" target=\"_blank\" rel=\"noopener\">Brandportal\u00a0<\/a><\/li>\n<\/ul>\n<p>Mit dem Online-Editor von CHILI publish k\u00f6nnen Sie Marketingmaterialien innerhalb von Vorlagen mit Ihrem eigenen Branding personalisieren. Prindustry integriert diesen Editor in seine Webshops und Brandportale. So k\u00f6nnen Unternehmen die Markenkommunikation nicht nur einfach bearbeiten, sondern auch verwalten, verkaufen und kaufen.<\/p>\n<h3>Kreative Automatisierung f\u00fcr die Markenkommunikation<\/h3>\n<p>Der Editor <a href=\"https:\/\/www.chili-publish.com\/grafx\/impact\/\" target=\"_blank\" rel=\"noopener\">GraFx Publisher<\/a> (fr\u00fcher bekannt als CHILI publisher) erm\u00f6glicht es Unternehmen, ihre Marke einheitlich und stark zu pr\u00e4sentieren. Der Editor bietet Vorlagen f\u00fcr Kommunikationsmaterialien, die variabel anpassbar sind. So muss eine Designvorlage f\u00fcr ein Produkt nur einmal erstellt werden. Darin sind die Markenkomponenten fixiert. Man denke nur an die Platzierung des Logos oder die Firmenfarben. Innerhalb dieses Rahmens kann ein Benutzer das Kommunikationsmaterial selbst anpassen und lokalisieren.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;52259&#8243; image_size=&#8220;portfolio-thumb&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; img_link_large=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;52256&#8243; image_size=&#8220;portfolio-thumb&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; img_link_large=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;1%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h3>Flexible Benutzeroberfl\u00e4che<\/h3>\n<p>Die Benutzeroberfl\u00e4che des Editors l\u00e4sst sich an die Bed\u00fcrfnisse und Kenntnisse des\/der Benutzer(s) anpassen, von einfach bis fortgeschritten. Die Benutzer k\u00f6nnen innerhalb von Sekunden Text bearbeiten, Bilder hinzuf\u00fcgen und variable Daten laden.<\/p>\n<h3>Kontrolle der Marke<\/h3>\n<p>Der Editor bietet Designs innerhalb von Markenvorlagen, die Markenelemente wie Farbe, Schriftart und Logo definieren. Innerhalb dieser Vorlagen k\u00f6nnen die Nutzer Bilder und Text variieren und dabei die Markenkonsistenz wahren.<\/p>\n<h3>Dynamische Smart Templates<\/h3>\n<p>Eine Smart-Vorlage kann viele verschiedene Formate auf einmal erzeugen. Im Hoch- oder Querformat. F\u00fcr Druck oder Web. Alle erstellten Entw\u00fcrfe werden automatisch gespeichert, sodass sie beim n\u00e4chsten Mal leicht wiederverwendet und angepasst werden k\u00f6nnen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;51237&#8243; image_size=&#8220;portfolio-thumb&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; img_link_large=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;51495&#8243; image_size=&#8220;portfolio-thumb&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; img_link_large=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;1%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h3>Print Output: druckfertige Datei<\/h3>\n<p>F\u00fcr den Offline-Druck erhalten Sie eine druckfertige PDF-Datei, die direkt in die Produktion gehen kann. Eine Visitenkarte, eine Brosch\u00fcre, eine Fahne oder ein Banner. Das PDF geht \u00fcber Verkn\u00fcpfungen im Prindustry<a href=\"https:\/\/prindustry.com\/de\/markenportal-loesungen\/\" target=\"_blank\" rel=\"noopener\"> Brand Portal<\/a> direkt an angeschlossene Druckereien.<\/p>\n<h3>Online Output: verschiedene Formate<\/h3>\n<p>Online-Kommunikationsmittel werden oft in verschiedenen Formaten ben\u00f6tigt. Ein Banner, ein Beitrag oder eine Story f\u00fcr Facebook hat andere Dimensionen und Anforderungen als f\u00fcr Instagram oder LinkedIn. Der Editor kann die verschiedenen Formate f\u00fcr die verschiedenen Sozialen Plattformen aus einer Vorlage generieren. Sie k\u00f6nnen die Bilder direkt downloaden und zu den Konten der Sozialen Medien hinzuf\u00fcgen.<\/p>\n<h3>Daten verkn\u00fcpfen<\/h3>\n<p>Mailinglisten k\u00f6nnen einfach mit dem Editor verkn\u00fcpft werden, so dass personalisierte Mailings erstellt werden k\u00f6nnen.<br \/>\nDas System kann auch direkt eigene (Standort-)Daten in eine Vorlage f\u00fcr jeden einzelnen Benutzer, der sich anmeldet, eingeben.<\/p>\n<h3>Adobe Plugin<\/h3>\n<p>Dokumente aus Adobe InDesign oder Illustrator k\u00f6nnen direkt in den Editor exportiert werden. Dar\u00fcber hinaus k\u00f6nnen Dokumente auch aus anderen Quellen wie PDFs oder XML-Dateien erstellt werden.<\/p>\n<h3>3D Vorschau<\/h3>\n<p>Die 3D-Visualisierung vermittelt Ihnen eine realistische Vorstellung davon, wie das individuelle Kommunikationsdesign aussehen wird.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;1%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;51504&#8243; image_size=&#8220;portfolio-thumb&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; img_link_large=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;51895&#8243; image_size=&#8220;portfolio-thumb&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; img_link_large=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;1%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;top&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][vc_column_text]\n<h3>CHILI und Prindustry<\/h3>\n<p>Der Online-Editor GraFx Publisher von CHILI l\u00e4sst sich nahtlos in das Prindustry <a href=\"https:\/\/prindustry.com\/de\/brand-portal-software\/\" target=\"_blank\" rel=\"noopener\">Brand Portal<\/a> und den <a href=\"https:\/\/prindustry.com\/de\/whitelabelshop\/\" target=\"_blank\" rel=\"noopener\">WhiteLabelShop<\/a> integrieren. CHILI verkn\u00fcpft bequem smarte Daten mit smarten Vorlagen und generiert druckfertige Ausgaben wie z.B. ein PDF. Prindustry \u00fcbernimmt dann die Aufgabe. Prindustry verkn\u00fcpft das PDF mit den Druckpartnern und der Produktion. So bieten CHILI und Prindustry eine Gesamtl\u00f6sung f\u00fcr das Kommunikationsmanagement.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220;][image_with_animation image_url=&#8220;50977&#8243; image_size=&#8220;portfolio-thumb&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; img_link_large=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]Dank der Integration von CHILI und Prindustry k\u00f6nnen sich die Benutzer in ihr Webportal einloggen und rund um die Uhr Kommunikationsmaterialien erstellen, herunterladen und bestellen, die sie an ihren eigenen Standorten verwenden k\u00f6nnen. Mit einem umfangreichen Angebot an Berechtigungen und Rollen k\u00f6nnen die Benutzer nur auf das zugreifen, was f\u00fcr sie relevant ist.<\/p>\n<p>Erfahren Sie mehr \u00fcber eine <a href=\"https:\/\/prindustry.com\/de\/online-demo-anfordern\/\" target=\"_blank\" rel=\"noopener\">Online-Demo<\/a>!<\/p>\n<ul>\n<li>Bevorzugen Sie einen weniger aufwendigen Editor f\u00fcr Ihren Endkunden oder ben\u00f6tigen Sie ein Design Tool f\u00fcr einen Webshop? Probieren Sie den <a href=\"https:\/\/prindustry.com\/de\/online-editor-pitchprint\/\" target=\"_blank\" rel=\"noopener\">PitchPrint-Editor<\/a> aus!<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;6%&#8220; bottom_padding=&#8220;6%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-8-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color=&#8220;#efefef&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;5px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;7\/12&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; gradient_type=&#8220;default&#8220;][vc_row_inner column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bottom_padding=&#8220;10&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; offset=&#8220;vc_col-lg-11 vc_col-md-11 vc_col-xs-12&#8243;][vc_custom_heading text=&#8220;M\u00f6chten Sie mehr Informationen?&#8220; font_container=&#8220;tag:h3|font_size:38|text_align:left|color:%23172e4b&#8220; use_theme_fonts=&#8220;yes&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; offset=&#8220;vc_col-lg-11 vc_col-md-11 vc_col-xs-12&#8243;][vc_column_text css=&#8220;.vc_custom_1751892265032{padding-right: 10% !important;}&#8220;]Wir erz\u00e4hlen Ihnen gerne mehr \u00fcber die Funktionen und M\u00f6glichkeiten dieses Editors in der Prindustry-Software![\/vc_column_text][nectar_btn size=&#8220;medium&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;fontawesome&#8220; text=&#8220;KONTAKT FORM&#8220; margin_top=&#8220;20px&#8220; url=&#8220;https:\/\/prindustry.com\/de\/kontakt\/&#8220; margin_right=&#8220;20px&#8220; icon_fontawesome=&#8220;fa fa-wpforms&#8220;][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;fontawesome&#8220; text=&#8220;CALL PRINDUSTRY&#8220; margin_top=&#8220;10px&#8220; url=&#8220;tel:+31208223536&#8243; icon_fontawesome=&#8220;fa fa-phone&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;5\/12&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;5px&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;22787&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Grow In&#8220; hover_animation=&#8220;zoom-crop&#8220; alignment=&#8220;right&#8220; border_radius=&#8220;5px&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;110%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_spacing=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":52262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88,91],"tags":[],"class_list":{"0":"post-9768","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brandportal-2-de","8":"category-online-editing-2-de"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online Editor CHILI publisher | Brandportal<\/title>\n<meta name=\"description\" content=\"CHILI publisher ist ein Online Editor, der sich einfach in den Workflow des Prindustry Markenportals integrieren l\u00e4sst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online Editor CHILI publisher | Brandportal\" \/>\n<meta property=\"og:description\" content=\"CHILI publisher ist ein Online Editor, der sich einfach in den Workflow des Prindustry Markenportals integrieren l\u00e4sst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/\" \/>\n<meta property=\"og:site_name\" content=\"Prindustry | Software Brandportals &amp; Webshops | We love to connect\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Prindustry\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-24T07:10:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T12:33:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prindustry.com\/wp-content\/uploads\/2024\/05\/CHILI-Publish-Prindustry-design-brand-template-editor.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jolanda_Prindustry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@prindustry\" \/>\n<meta name=\"twitter:site\" content=\"@prindustry\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jolanda_Prindustry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online Editor CHILI publisher | Brandportal","description":"CHILI publisher ist ein Online Editor, der sich einfach in den Workflow des Prindustry Markenportals integrieren l\u00e4sst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/","og_locale":"de_DE","og_type":"article","og_title":"Online Editor CHILI publisher | Brandportal","og_description":"CHILI publisher ist ein Online Editor, der sich einfach in den Workflow des Prindustry Markenportals integrieren l\u00e4sst.","og_url":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/","og_site_name":"Prindustry | Software Brandportals &amp; Webshops | We love to connect","article_publisher":"https:\/\/www.facebook.com\/Prindustry\/","article_published_time":"2024-05-24T07:10:27+00:00","article_modified_time":"2026-07-10T12:33:45+00:00","og_image":[{"width":1000,"height":522,"url":"https:\/\/prindustry.com\/wp-content\/uploads\/2024\/05\/CHILI-Publish-Prindustry-design-brand-template-editor.webp","type":"image\/webp"}],"author":"Jolanda_Prindustry","twitter_card":"summary_large_image","twitter_creator":"@prindustry","twitter_site":"@prindustry","twitter_misc":{"Verfasst von":"Jolanda_Prindustry","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/#article","isPartOf":{"@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/"},"author":{"name":"Jolanda_Prindustry","@id":"https:\/\/prindustry.com\/de\/#\/schema\/person\/3befcaabb24ea4ea2dc368ec4cff0b68"},"headline":"CHILI: Konsistente Markenkommunikation","datePublished":"2024-05-24T07:10:27+00:00","dateModified":"2026-07-10T12:33:45+00:00","mainEntityOfPage":{"@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/"},"wordCount":3197,"image":{"@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/#primaryimage"},"thumbnailUrl":"https:\/\/prindustry.com\/wp-content\/uploads\/2024\/05\/CHILI-Publish-Prindustry-design-brand-template-editor.webp","articleSection":["Brandportal","Online-Editoren"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/","url":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/","name":"Online Editor CHILI publisher | Brandportal","isPartOf":{"@id":"https:\/\/prindustry.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/#primaryimage"},"image":{"@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/#primaryimage"},"thumbnailUrl":"https:\/\/prindustry.com\/wp-content\/uploads\/2024\/05\/CHILI-Publish-Prindustry-design-brand-template-editor.webp","datePublished":"2024-05-24T07:10:27+00:00","dateModified":"2026-07-10T12:33:45+00:00","author":{"@id":"https:\/\/prindustry.com\/de\/#\/schema\/person\/3befcaabb24ea4ea2dc368ec4cff0b68"},"description":"CHILI publisher ist ein Online Editor, der sich einfach in den Workflow des Prindustry Markenportals integrieren l\u00e4sst.","breadcrumb":{"@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/#primaryimage","url":"https:\/\/prindustry.com\/wp-content\/uploads\/2024\/05\/CHILI-Publish-Prindustry-design-brand-template-editor.webp","contentUrl":"https:\/\/prindustry.com\/wp-content\/uploads\/2024\/05\/CHILI-Publish-Prindustry-design-brand-template-editor.webp","width":1000,"height":522},{"@type":"BreadcrumbList","@id":"https:\/\/prindustry.com\/de\/online-editor-chili-publisher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prindustry.com\/de\/"},{"@type":"ListItem","position":2,"name":"CHILI: Konsistente Markenkommunikation"}]},{"@type":"WebSite","@id":"https:\/\/prindustry.com\/de\/#website","url":"https:\/\/prindustry.com\/de\/","name":"Prindustry | Software Brandportals &amp; Webshops | We love to connect","description":"We love to connect","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prindustry.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/prindustry.com\/de\/#\/schema\/person\/3befcaabb24ea4ea2dc368ec4cff0b68","name":"Jolanda_Prindustry","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/135a0dbeede4bf0c02f151910aeec47217518d582ba2c94e519e94e9c9dd6365?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/135a0dbeede4bf0c02f151910aeec47217518d582ba2c94e519e94e9c9dd6365?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/135a0dbeede4bf0c02f151910aeec47217518d582ba2c94e519e94e9c9dd6365?s=96&d=mm&r=g","caption":"Jolanda_Prindustry"},"description":"Verhalenverteller | Bedrijfsjournalist | Communicatiemanager | Dagdromer | MKB | Printmedia | Marketing | IT. Jolanda is een ervaren communicatie-expert die boeiende berichten brengt daar waar de ontvanger ze leest.","url":"https:\/\/prindustry.com\/de\/author\/jolanda_prindustry\/"}]}},"_links":{"self":[{"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/posts\/9768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/comments?post=9768"}],"version-history":[{"count":4,"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/posts\/9768\/revisions"}],"predecessor-version":[{"id":52277,"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/posts\/9768\/revisions\/52277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/media\/52262"}],"wp:attachment":[{"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/media?parent=9768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/categories?post=9768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prindustry.com\/de\/wp-json\/wp\/v2\/tags?post=9768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}